{"id":23291,"date":"2025-04-03T14:21:52","date_gmt":"2025-04-03T13:25:33","guid":{"rendered":"https:\/\/eurotrail.info\/?post_type=product&#038;p=23291"},"modified":"2025-04-03T14:25:34","modified_gmt":"2025-04-03T13:25:34","slug":"tazas-murcia-4-pcs-melamine","status":"publish","type":"product","link":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/","title":{"rendered":"Tazas Murcia 4 pcs melamine"},"content":{"rendered":"<p>El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.<br \/>\nCada taza tiene una capacidad de 300 ml y es resistente al calor hasta 70 grados cent\u00edgrados.<br \/>\nDise\u00f1adas para mayor comodidad, estas tazas son aptas para lavavajillas (solo en la rejilla superior) y son perfectas para cualquier aventura.<br \/>\nVajilla murciana a juego.<\/p>\n<p>4 tazas, 8,5 x 10,5 cm, 300 ml<\/p>\n<p>100% melamina<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.&hellip;<\/p>\n","protected":false},"featured_media":23272,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[337,345],"product_tag":[],"class_list":["post-23291","product","type-product","status-publish","has-post-thumbnail","product_cat-domestico","product_cat-vajilla","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tazas Murcia 4 pcs melamine - Eurotrail | The way we camp!<\/title>\n<meta name=\"description\" content=\"El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tazas Murcia 4 pcs melamine - Eurotrail | The way we camp!\" \/>\n<meta property=\"og:description\" content=\"El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurotrail | The way we camp!\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-03T13:25:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eurotrail.info\/wp\/wp-content\/uploads\/2025\/04\/set-C-beker.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2111\" \/>\n\t<meta property=\"og:image:height\" content=\"2152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/\",\"url\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/\",\"name\":\"Tazas Murcia 4 pcs melamine - Eurotrail | The way we camp!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eurotrail.info\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eurotrail.info\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/set-C-beker.jpg\",\"datePublished\":\"2025-04-03T13:25:33+00:00\",\"dateModified\":\"2025-04-03T13:25:34+00:00\",\"description\":\"El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eurotrail.info\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/set-C-beker.jpg\",\"contentUrl\":\"https:\\\/\\\/eurotrail.info\\\/wp\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/set-C-beker.jpg\",\"width\":2111,\"height\":2152,\"caption\":\"Murcia Bekers 4 st. melamine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/producten\\\/domestico\\\/vajilla\\\/tazas-murcia-4-pcs-melamine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/eurotrail.info\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tazas Murcia 4 pcs melamine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eurotrail.info\\\/#website\",\"url\":\"https:\\\/\\\/eurotrail.info\\\/\",\"name\":\"Eurotrail | The way we camp!\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eurotrail.info\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eurotrail.info\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eurotrail.info\\\/#organization\",\"name\":\"Eurotrail | The way we camp!\",\"url\":\"https:\\\/\\\/eurotrail.info\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/eurotrail.info\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eurotrail.info\\\/wp\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ET-logo-quote_NL-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/eurotrail.info\\\/wp\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/ET-logo-quote_NL-scaled.jpg\",\"width\":2560,\"height\":675,\"caption\":\"Eurotrail | The way we camp!\"},\"image\":{\"@id\":\"https:\\\/\\\/eurotrail.info\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tazas Murcia 4 pcs melamine - Eurotrail | The way we camp!","description":"El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/","og_locale":"es_ES","og_type":"article","og_title":"Tazas Murcia 4 pcs melamine - Eurotrail | The way we camp!","og_description":"El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.","og_url":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/","og_site_name":"Eurotrail | The way we camp!","article_modified_time":"2025-04-03T13:25:34+00:00","og_image":[{"width":2111,"height":2152,"url":"https:\/\/eurotrail.info\/wp\/wp-content\/uploads\/2025\/04\/set-C-beker.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/","url":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/","name":"Tazas Murcia 4 pcs melamine - Eurotrail | The way we camp!","isPartOf":{"@id":"https:\/\/eurotrail.info\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/#primaryimage"},"image":{"@id":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/#primaryimage"},"thumbnailUrl":"https:\/\/eurotrail.info\/wp\/wp-content\/uploads\/2025\/04\/set-C-beker.jpg","datePublished":"2025-04-03T13:25:33+00:00","dateModified":"2025-04-03T13:25:34+00:00","description":"El juego de 4 tazas Murcia es una opci\u00f3n elegante y pr\u00e1ctica para cenar al aire libre, fabricado con melamina 100 % libre de BPA.","breadcrumb":{"@id":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/#primaryimage","url":"https:\/\/eurotrail.info\/wp\/wp-content\/uploads\/2025\/04\/set-C-beker.jpg","contentUrl":"https:\/\/eurotrail.info\/wp\/wp-content\/uploads\/2025\/04\/set-C-beker.jpg","width":2111,"height":2152,"caption":"Murcia Bekers 4 st. melamine"},{"@type":"BreadcrumbList","@id":"https:\/\/eurotrail.info\/es\/producten\/domestico\/vajilla\/tazas-murcia-4-pcs-melamine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eurotrail.info\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/eurotrail.info\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Tazas Murcia 4 pcs melamine"}]},{"@type":"WebSite","@id":"https:\/\/eurotrail.info\/#website","url":"https:\/\/eurotrail.info\/","name":"Eurotrail | The way we camp!","description":"","publisher":{"@id":"https:\/\/eurotrail.info\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eurotrail.info\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/eurotrail.info\/#organization","name":"Eurotrail | The way we camp!","url":"https:\/\/eurotrail.info\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/eurotrail.info\/#\/schema\/logo\/image\/","url":"https:\/\/eurotrail.info\/wp\/wp-content\/uploads\/2023\/07\/ET-logo-quote_NL-scaled.jpg","contentUrl":"https:\/\/eurotrail.info\/wp\/wp-content\/uploads\/2023\/07\/ET-logo-quote_NL-scaled.jpg","width":2560,"height":675,"caption":"Eurotrail | The way we camp!"},"image":{"@id":"https:\/\/eurotrail.info\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/product\/23291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/comments?post=23291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/media\/23272"}],"wp:attachment":[{"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/media?parent=23291"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/product_brand?post=23291"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/product_cat?post=23291"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eurotrail.info\/es\/wp-json\/wp\/v2\/product_tag?post=23291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}